{"id":11520,"date":"2023-07-26T10:09:16","date_gmt":"2023-07-26T08:09:16","guid":{"rendered":"https:\/\/bfqhbmyrq.preview.infomaniak.website\/portfolio-item\/association-autrement-aujourdhui\/"},"modified":"2024-05-02T21:30:03","modified_gmt":"2024-05-02T19:30:03","slug":"association-autrement-aujourdhui","status":"publish","type":"portfolio-item","link":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/","title":{"rendered":"Association Autrement-Aujourd&#8217;hui"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11520\" class=\"elementor elementor-11520 elementor-11334\" data-elementor-post-type=\"portfolio-item\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1448cbb6 qodef-elementor-content-grid elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1448cbb6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44364cf9 qodef-sticky-column--no\" data-id=\"44364cf9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3441fde3 elementor-widget elementor-widget-spacer\" data-id=\"3441fde3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38fe8a62 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"38fe8a62\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-55d0a0c1 qodef-sticky-column--no\" data-id=\"55d0a0c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195db2a3 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"195db2a3\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h1 class=\"qodef-m-title\">\n\t\tAssociation Autrement-aujourd'hui\t<\/h1>\n\t\t\t<div class=\"qodef-m-text\"><p><strong>a<\/strong>utrement-<strong>a<\/strong>ujourd\u2019hui est une association sans but lucratif, fond\u00e9e \u00e0 Gen\u00e8ve fin 1981 pour d\u00e9velopper une recherche et une pratique dans le domaine de l\u2019expression artistique avec des personnes en situation de handicap mental ou ayant des troubles d'apprentissage.<\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-684619c8 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"684619c8\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\tNature du projet\t<\/h2>\n\t\t\t<div class=\"qodef-m-text\"><p>Soutien \u00e0 la programmation 2022<\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9ee6fb elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"5a9ee6fb\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\tDescription\t<\/h2>\n\t\t\t<div class=\"qodef-m-text\"><div class=\"ewa-rteLine\"><p>S'adressant \u00e0 des adultes aussi bien qu'\u00e0 des adolescents, cette d\u00e9marche est men\u00e9e selon des options pr\u00e9cises:<\/p><ul><li>Proposer une initiation et une formation dans les domaines du th\u00e9\u00e2tre, de la danse et de la musique r\u00e9pondant aux exigences de ce type d'activit\u00e9.<\/li><li>Situer clairement son action sur le plan artistique et culturel.<\/li><li>D\u00e9velopper autour des ateliers et selon une perspective plus globale un espace de vie en relation avec les buts poursuivis. Celui-ci comprend \u00e9galement des projets d'approches d'autres domaines artistiques et\/ou artisanaux.<\/li><li>R\u00e9aliser p\u00e9riodiquement des productions ouvertes au public: pr\u00e9sentations d\u2019ateliers, interventions th\u00e9\u00e2trales, r\u00e9alisations interm\u00e9diaires, concerts, spectacles publics en partenariat avec les th\u00e9\u00e2tres de la cit\u00e9.<\/li><li>Favoriser un regard nouveau sur les personnes en situation de handicap mental et permettre, par le biais de r\u00e9alisations, une rencontre entre des univers diff\u00e9rents, tout en marquant des \u00e9tapes dans une recherche de formes artistiques contemporaines.<\/li><\/ul><p><em><strong>Soutenir les activit\u00e9s\u00a0 developp\u00e9es hors des structures institutionnelles (Th\u00e9\u00e2tre de l'Esquisse &amp; Atelier Th\u00e9\u00e2tre Insolite, Atelier Musique &amp; Son-O'Rythme).<\/strong><\/em><\/p><\/div><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b3a3c85 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"1b3a3c85\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h2 class=\"qodef-m-title\">\n\t\tSite Internet \t<\/h2>\n\t\t\t<div class=\"qodef-m-text\"><div class=\"website-link\"><a href=\"https:\/\/www.operadeparis.fr\/academie\/education-artistique\/operapprentis-1\" target=\"_blank\" rel=\"noopener\">https:\/\/www.<\/a><a href=\"http:\/\/www.autrement-aujourdhui.ch\/\">autrement-aujourdhui.ch<\/a><\/div><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc47a2 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery\" data-id=\"2fc47a2\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery qodef-qi-grid qodef-layout--qi-columns qodef-col-num--4 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2632\" height=\"1408\" src=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/F_SDG_logo_without_UN_emblem_Square_WEB.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/F_SDG_logo_without_UN_emblem_Square_WEB.png 2632w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/F_SDG_logo_without_UN_emblem_Square_WEB-300x160.png 300w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/F_SDG_logo_without_UN_emblem_Square_WEB-1024x548.png 1024w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/F_SDG_logo_without_UN_emblem_Square_WEB-768x411.png 768w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/F_SDG_logo_without_UN_emblem_Square_WEB-1536x822.png 1536w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/F_SDG_logo_without_UN_emblem_Square_WEB-2048x1096.png 2048w\" sizes=\"(max-width: 2632px) 100vw, 2632px\" \/>\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre.png 1500w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre-300x300.png 300w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre-1024x1024.png 1024w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre-150x150.png 150w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre-768x768.png 768w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre-650x650.png 650w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Sante-et-Bien-etre-1300x1300.png 1300w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"1500\" src=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites.png 1500w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites-300x300.png 300w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites-1024x1024.png 1024w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites-150x150.png 150w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites-768x768.png 768w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites-650x650.png 650w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/04\/Inegalites-reduites-1300x1300.png 1300w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a3552 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"29a3552\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-section-title qodef-decoration--italic qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t\t\t<div class=\"qodef-m-text\"><p><em><strong>Les 17 objectifs de d\u00e9veloppement<\/strong> <strong>durable<\/strong> tels que <strong>d\u00e9finis par les Nations Unies<\/strong> nous donnent la marche \u00e0 suivre pour parvenir \u00e0 un avenir meilleur et plus durable pour tous. Ils r\u00e9pondent aux d\u00e9fis mondiaux auxquels nous sommes confront\u00e9s, notamment ceux li\u00e9s \u00e0 la pauvret\u00e9, aux in\u00e9galit\u00e9s, au climat, \u00e0 la d\u00e9gradation de l\u2019environnement, \u00e0 la prosp\u00e9rit\u00e9, \u00e0 la paix et \u00e0 la justice. Les objectifs sont interconnect\u00e9s et, pour ne laisser personne de c\u00f4t\u00e9, <strong>il est important d\u2019atteindre chacun d\u2019entre eux<\/strong>, et chacune de leurs cibles,<strong> d\u2019ici \u00e0 2030<\/strong>.<\/em><\/p><\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4f5c06e8 qodef-sticky-column--no\" data-id=\"4f5c06e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a782da0 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"7a782da0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"336\" src=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-1.jpg\" class=\"attachment-full size-full wp-image-11339\" alt=\"\" srcset=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-1.jpg 448w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-1-300x225.jpg 300w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43a4a566 elementor-widget-mobile__width-initial elementor-widget-tablet__width-auto elementor-widget elementor-widget-image\" data-id=\"43a4a566\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.operadeparis.fr\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"270\" src=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-3.jpg\" class=\"attachment-full size-full wp-image-11345\" alt=\"\" srcset=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-3.jpg 448w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-3-300x181.jpg 300w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4e8e5caf qodef-sticky-column--no\" data-id=\"4e8e5caf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5876dfa4 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"5876dfa4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"448\" height=\"321\" src=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-2.jpg\" class=\"attachment-full size-full wp-image-11342\" alt=\"\" srcset=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-2.jpg 448w, https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-2-300x215.jpg 300w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60bd14cc elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"60bd14cc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b5e92d7 qodef-sticky-column--no\" data-id=\"5b5e92d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d4b64b elementor-widget__width-auto elementor-widget elementor-widget-global elementor-global-10711 elementor-global-7830 elementor-widget-qi_addons_for_elementor_button\" data-id=\"0d4b64b\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--textual qodef-icon--right qodef-hover--icon-move-horizontal-short qodef-text-underline qodef-underline--left\" href=\"\/demandes\/#submit-project\" target=\"_self\">\n\t<span class=\"qodef-m-text\">Reichen Sie Ihr Projekt ein<\/span>\n\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Soutien \u00e0 la programmation 2022<\/p>\n","protected":false},"author":8,"featured_media":11362,"menu_order":8,"template":"elementor_theme","portfolio-category":[49],"portfolio-tag":[],"class_list":["post-11520","portfolio-item","type-portfolio-item","status-publish","has-post-thumbnail","hentry","years-78","portfolio-category-zweck-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Association Autrement-Aujourd&#039;hui - Carigest SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Association Autrement-Aujourd&#039;hui - Carigest SA\" \/>\n<meta property=\"og:description\" content=\"Soutien \u00e0 la programmation 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/\" \/>\n<meta property=\"og:site_name\" content=\"Carigest SA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T19:30:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"722\" \/>\n\t<meta property=\"og:image:height\" content=\"115\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/\",\"url\":\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/\",\"name\":\"Association Autrement-Aujourd'hui - Carigest SA\",\"isPartOf\":{\"@id\":\"https:\/\/carigest.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg\",\"datePublished\":\"2023-07-26T08:09:16+00:00\",\"dateModified\":\"2024-05-02T19:30:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#primaryimage\",\"url\":\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg\",\"contentUrl\":\"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg\",\"width\":722,\"height\":115},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/carigest.ch\/de\/startseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qode Portfolio\",\"item\":\"https:\/\/carigest.ch\/de\/portfolio-item\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Association Autrement-Aujourd&#8217;hui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/carigest.ch\/de\/#website\",\"url\":\"https:\/\/carigest.ch\/de\/\",\"name\":\"Carigest SA\",\"description\":\"Beratung, Verwaltung, Begleitung\",\"publisher\":{\"@id\":\"https:\/\/carigest.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/carigest.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/carigest.ch\/de\/#organization\",\"name\":\"Carigest SA\",\"url\":\"https:\/\/carigest.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/carigest.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Carigest SA\"},\"image\":{\"@id\":\"https:\/\/carigest.ch\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/carigest-sa\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association Autrement-Aujourd'hui - Carigest SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/","og_locale":"de_DE","og_type":"article","og_title":"Association Autrement-Aujourd'hui - Carigest SA","og_description":"Soutien \u00e0 la programmation 2022","og_url":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/","og_site_name":"Carigest SA","article_modified_time":"2024-05-02T19:30:03+00:00","og_image":[{"width":722,"height":115,"url":"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/","url":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/","name":"Association Autrement-Aujourd'hui - Carigest SA","isPartOf":{"@id":"https:\/\/carigest.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#primaryimage"},"image":{"@id":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#primaryimage"},"thumbnailUrl":"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg","datePublished":"2023-07-26T08:09:16+00:00","dateModified":"2024-05-02T19:30:03+00:00","breadcrumb":{"@id":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#primaryimage","url":"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg","contentUrl":"https:\/\/carigest.ch\/wp-content\/uploads\/2023\/07\/autrement-aujourdhui-5.jpg","width":722,"height":115},{"@type":"BreadcrumbList","@id":"https:\/\/carigest.ch\/de\/portfolio-item\/association-autrement-aujourdhui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/carigest.ch\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Qode Portfolio","item":"https:\/\/carigest.ch\/de\/portfolio-item\/"},{"@type":"ListItem","position":3,"name":"Association Autrement-Aujourd&#8217;hui"}]},{"@type":"WebSite","@id":"https:\/\/carigest.ch\/de\/#website","url":"https:\/\/carigest.ch\/de\/","name":"Carigest SA","description":"Beratung, Verwaltung, Begleitung","publisher":{"@id":"https:\/\/carigest.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carigest.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/carigest.ch\/de\/#organization","name":"Carigest SA","url":"https:\/\/carigest.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/carigest.ch\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Carigest SA"},"image":{"@id":"https:\/\/carigest.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/carigest-sa\/"]}]}},"_links":{"self":[{"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/portfolio-item\/11520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/portfolio-item"}],"about":[{"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/types\/portfolio-item"}],"author":[{"embeddable":true,"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":4,"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/portfolio-item\/11520\/revisions"}],"predecessor-version":[{"id":12878,"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/portfolio-item\/11520\/revisions\/12878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/media\/11362"}],"wp:attachment":[{"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/media?parent=11520"}],"wp:term":[{"taxonomy":"portfolio-category","embeddable":true,"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/portfolio-category?post=11520"},{"taxonomy":"portfolio-tag","embeddable":true,"href":"https:\/\/carigest.ch\/de\/wp-json\/wp\/v2\/portfolio-tag?post=11520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}